{"id":23888,"date":"2026-09-02T07:22:29","date_gmt":"2026-09-02T05:22:29","guid":{"rendered":"http:\/\/www.on4cn.be\/blog_radio\/?p=23888"},"modified":"2026-09-02T07:22:29","modified_gmt":"2026-09-02T05:22:29","slug":"information-p29yy-papouasie-nouvelle-guinee-3","status":"publish","type":"post","link":"http:\/\/www.on4cn.be\/blog_radio\/2026\/09\/02\/information-p29yy-papouasie-nouvelle-guinee-3\/","title":{"rendered":"Information P29YY, Papouasie-Nouvelle-Guin\u00e9e"},"content":{"rendered":"<article class=\"article\">\n<center><b><span style=\"color: #0000ff;\">Article traduite en Fran\u00e7ais via Google Translate<\/b><\/span><\/center><br \/> <br \/>\n<center><strong><span style=\"color: #ff0000;\"><\/p>\n<h2>Information P29YY, Papouasie-Nouvelle-Guin\u00e9e<\/h2>\n<p><\/span><\/strong><\/center><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEjCUg5cG4P0R0XVU8QXxHPkKjnlurksGiK2vMZiH5BJrp2vS5KQ64qmQ2GSm8J8HlXmZpVJCMbWHDMZu8uULBy7572MbgWWS-drS9M0mEAkc5SWvHwkXZHh_uzI_AiFv_P1gUfFpS3vZB0G-ZeBV-ElSTbkupxksJjB82tvoI6tzoY9LjZj9r2i\/s1600\/p29yy%20qth.jpeg\" alt=\"P29YY, Papouasie-Nouvelle-Guin\u00e9e\" width=\"600\" height=\"350\" \/><\/p>\n<p><b>Le 02 Septembre 2026<\/b><\/p>\n<p><b>( Maxim \/ 1er SEPTEMBRE 2026 )<\/b><\/p>\n<p style=\"text-align: justify;\">Il est extr\u00eamement frustrant de devoir courir apr\u00e8s le personnel et les supplier de me donner de l\u2019\u00e9lectricit\u00e9, en leur rappelant et en leur demandant encore et encore. \u00ab Dans 5 minutes \u00bb, et voil\u00e0 d\u00e9j\u00e0 une heure qui s\u2019est \u00e9coul\u00e9e sans que je puisse faire quoi que ce soit de productif. Les gens sont \u00e0 moiti\u00e9 endormis. Je suis une nuisance pour eux, pas un client bienvenu\u2026 Quelle gal\u00e8re !<\/p>\n<p style=\"text-align: justify;\">J\u2019ai op\u00e9r\u00e9 pendant 2 heures, mais ensuite l\u2019ordinateur portable, qui \u00e9tait partiellement charg\u00e9, s\u2019est \u00e9teint, et j\u2019ai perdu 2 heures \u00e0 attendre et \u00e0 les convaincre de d\u00e9marrer ce fichu g\u00e9n\u00e9rateur. Nous vivons selon des rythmes temporels tr\u00e8s diff\u00e9rents.<\/p>\n<p style=\"text-align: justify;\">Comme pr\u00e9vu, un magnifique VDA de 15 m a rejoint sa grande s\u0153ur.<\/p>\n<p style=\"text-align: justify;\">Bienvenue dans l\u2019automne 2026 !<\/p>\n<p style=\"text-align: justify;\">La nuit a \u00e9t\u00e9 compl\u00e8tement folle.<\/p>\n<p style=\"text-align: justify;\">J\u2019avais promis de commencer en SSB, et la bande des 20 m + VDA \u00e9tait la plus facile pour entrer en action\u2026 Puis j\u2019ai trouv\u00e9 une station bruyante qui parlait de pr\u00e9f\u00e9rences culinaires (\u00ab J\u2019aime \u00e7a, mais je n\u2019aime pas les haricots ni les petits pois \u00bb) pendant plusieurs minutes sans donner son indicatif\u2026 J\u2019ai donc d\u00e9cid\u00e9 de rejoindre poliment la conversation en annon\u00e7ant P29YY. \u00c0 la voix, la station \u00e9tait am\u00e9ricaine\u2026 Elle me disait quelque chose, mais il y a plus de 300 millions d\u2019Am\u00e9ricains, et je ne suis pas anglophone natif\u2026<\/p>\n<p style=\"text-align: justify;\">Eh bien, il s\u2019est av\u00e9r\u00e9 que c\u2019\u00e9tait mon vieil ami Stan (KE5EE) ! C\u2019\u00e9tait incroyable ! Je suis tomb\u00e9 par hasard sur une connaissance avec son premier indicatif SSB, P29YY. Je suis rest\u00e9 stup\u00e9fait. Il y a des choses vraiment trop \u00e9tranges\u2026 Ce fut une conversation tr\u00e8s anim\u00e9e, et nous avons r\u00e9uni un bon groupe d\u2019auditeurs (surprise !). Le signal \u00e9tait S9+ dans les deux directions. Stan a gentiment partag\u00e9 la fr\u00e9quence et est retourn\u00e9 \u00e0 sa routine habituelle, puisque c\u2019\u00e9tait le matin pour lui et la nuit pour moi. J\u2019ai op\u00e9r\u00e9 sur 20 m\u00e8tres, de 5 \u00e0 15 kHz, jusqu\u2019\u00e0 2 heures du matin. Je pensais faire un petit \u00e9chauffement pour v\u00e9rifier que tout fonctionnait, mais je ne m\u2019attendais pas \u00e0 devoir affronter une avalanche d\u2019appels. \u00c0 2 heures du matin, j\u2019\u00e9tais \u00e9puis\u00e9, sachant que j\u2019avais commenc\u00e9 \u00e0 6 h 40 et que, dans 95 % des cas, c\u2019est un moment o\u00f9 l\u2019adr\u00e9naline est \u00e0 son maximum : r\u00e9parer, r\u00e9soudre, convaincre, r\u00e9parer \u00e0 nouveau, et recommencer. Mais ensuite, je comptais activer le FT8 sur 80 m et aller dormir\u2026<\/p>\n<p style=\"text-align: justify;\">Ah ! Facile, n\u2019est-ce pas ? \u2014 Pas toujours\u2026 Windows a d\u00e9cid\u00e9 que WSJT-Z \u00e9tait un virus et a supprim\u00e9 certains de ses fichiers. Le r\u00e9parer, le r\u00e9installer, ou m\u00eame t\u00e9l\u00e9charger le nouveau fichier et tenter une nouvelle installation n\u2019a servi \u00e0 rien\u2026 \u00c0 4 heures du matin, j\u2019ai finalement r\u00e9ussi \u00e0 installer l\u2019ancienne version. Le dernier probl\u00e8me est que Windows la bloque compl\u00e8tement. Mais \u00e0 4 heures du matin, cela n\u2019avait plus aucun sens de continuer \u00e0 se battre, puisque le courant devait \u00eatre coup\u00e9 vers 6 h 30 ou quelque chose comme \u00e7a.<\/p>\n<p style=\"text-align: justify;\">Je n\u2019ai pas encore v\u00e9rifi\u00e9 les journaux ; il n\u2019y a pas le temps de faire quoi que ce soit ; je continue simplement d\u2019avancer sans r\u00e9fl\u00e9chir, \u00e0 vrai dire.<\/p>\n<p style=\"text-align: justify;\">Le matin devient une routine : r\u00e9parer ce qui s\u2019est cass\u00e9. Red\u00e9marrer tout ce qui s\u2019est bloqu\u00e9. Surveiller et recommencer lorsqu\u2019un nouvel \u00e9l\u00e9ment tombe en panne.<\/p>\n<p style=\"text-align: justify;\">Qu\u2019est-ce qui s\u2019est cass\u00e9 pendant la nuit ? Eh bien, les radiales sur\u00e9lev\u00e9s vont bien, mais c\u2019est un enchev\u00eatrement complexe et \u00e0 peine visible de c\u00e2bles et de fils en Kevlar. Il y en a donc toujours 2 ou 3 d\u2019endommag\u00e9s ; ils ne sont pas cass\u00e9s, mais les c\u00e2bles se retrouvent au sol. J\u2019ai donc r\u00e9par\u00e9 et r\u00e9ajust\u00e9 le ROS une nouvelle fois ; la partie sup\u00e9rieure du VDA de 20 m s\u2019est effondr\u00e9e. Je pense qu\u2019il me manquait un morceau de ruban adh\u00e9sif sur l\u2019une des sections. L\u2019antenne VDA de 20 m\u00e8tres sera donc d\u00e9mont\u00e9e et r\u00e9par\u00e9e, et celle de 15 m\u00e8tres sera ajout\u00e9e, ce qui \u00e9tait d\u00e9j\u00e0 pr\u00e9vu.<\/p>\n<p style=\"text-align: justify;\">Bien s\u00fbr, \u00e0 10 h 30, ils ont coup\u00e9 le courant principal et je suis pass\u00e9 sur batterie pour la radio et l\u2019ordinateur DX.<\/p>\n<p style=\"text-align: justify;\">La bande des 12 m\u00e8tres est relativement peu peupl\u00e9e, mais celle des 17 m\u00e8tres fonctionne tr\u00e8s bien.<\/p>\n<p style=\"text-align: justify;\">Je vais commencer \u00e0 op\u00e9rer davantage en SSB.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEgz0lYSw3Jei7X72Kkt8ZVgSb2DhyauaNltYU2EkwKbML10MxVCcwiQsLWFo5FdFiWEV_OP9DORDdH2Ero2hci6CD51pi9JOXzJnwKU7ZzIpF_2Rm2RwgIgwtm6ugc1SILeV5Rc5HNTvHI2520Yl95yYIBfPrC1uYbr0LATtRBpOzaYRI8_Gt9-\/s1536\/p29yy%20ant.jpeg\" style=\"margin-left: 1em; margin-right: 1em;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"600\" width=\"400\" height=\"600\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEgz0lYSw3Jei7X72Kkt8ZVgSb2DhyauaNltYU2EkwKbML10MxVCcwiQsLWFo5FdFiWEV_OP9DORDdH2Ero2hci6CD51pi9JOXzJnwKU7ZzIpF_2Rm2RwgIgwtm6ugc1SILeV5Rc5HNTvHI2520Yl95yYIBfPrC1uYbr0LATtRBpOzaYRI8_Gt9-\/w480-h640\/p29yy%20ant.jpeg\" width=\"480\"><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEjjGWO2yYP50DW0c2Zb0tBy_kGvFr7vfHs0ANjhwRfHSlm6kAA3BMBo5zTg8LiED2khivBtXaGIjtaRytETP7Df9l_eYuQ1VCkAFPFmryjCNCaFea9cNO3hmQC4-L6jDZvhXsCwVWetBhezB6_tlyI2f0uV5WjDewXS78_gzioUov9efTaU2-PA\/s1537\/p29yy%202.png\" style=\"margin-left: 1em; margin-right: 1em;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"400\" width=\"600\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEjjGWO2yYP50DW0c2Zb0tBy_kGvFr7vfHs0ANjhwRfHSlm6kAA3BMBo5zTg8LiED2khivBtXaGIjtaRytETP7Df9l_eYuQ1VCkAFPFmryjCNCaFea9cNO3hmQC4-L6jDZvhXsCwVWetBhezB6_tlyI2f0uV5WjDewXS78_gzioUov9efTaU2-PA\/s1600\/p29yy%202.png\"><\/a><\/p>\n<p style=\"text-align: center;\"><b>( Maxim \/ 29 AO\u00dbT 2026 )<\/b><\/p>\n<p style=\"text-align: justify;\">J\u2019ai r\u00e9ussi \u00e0 entrer en Papouasie-Nouvelle-Guin\u00e9e, ce qui n\u2019\u00e9tait pas garanti il y a encore quelques jours. Je suis toujours \u00e0 Port Moresby. Mais mon \u00e9quipement est \u00e9galement arriv\u00e9, ce qui est prometteur. Je dois rejoindre ma destination finale, Kavieng, cet apr\u00e8s-midi. Je pr\u00e9vois d\u2019installer quelques antennes aujourd\u2019hui m\u00eame et de commencer \u00e0 op\u00e9rer, au moins en FT8, en esp\u00e9rant qu\u2019il y ait un niveau raisonnable de perturbations locales. Nous verrons bien\u2026<\/p>\n<p style=\"text-align: justify;\">Si tout se passe bien, je serai tr\u00e8s actif \u00e0 partir de demain.<\/p>\n<p style=\"text-align: justify;\"><b>Modes et antennes :<\/b><\/p>\n<ul>\n<li>Toutes les antennes de 160 m \u00e0 10 m sont avec moi. De 80 \u00e0 10 m, c\u2019est certain. Pour le 160 m, nous verrons si l\u2019antenne peut \u00eatre correctement accord\u00e9e.<\/li>\n<li>20\/17\/15 m : antennes VDA.<\/li>\n<li>Autres bandes : verticales avec radiales sur\u00e9lev\u00e9s.<\/li>\n<li>Toutes les antennes seront \u00e0 quelques m\u00e8tres de la mer : c\u2019est mon grand espoir. Mais je ne suis pas encore arriv\u00e9 \u00e0 ma destination finale.<\/li>\n<li>Icom 7300. Mais en mode d\u2019utilisation locale \u00e0 distance : le transceiver est install\u00e9 pr\u00e8s de la c\u00f4te, tandis que je me trouve \u00e0 environ 30 \u00e0 100 m\u00e8tres, dans ma chambre. Nous verrons bien. Cela a fonctionn\u00e9 en 8Q7YY. J\u2019esp\u00e8re pouvoir reproduire la m\u00eame configuration ici. Tout est pr\u00eat pour cela. Encore une fois, l\u2019objectif principal est de minimiser les interf\u00e9rences locales et d\u2019\u00eatre aussi proche que possible de la mer.<\/li>\n<li>SSB et FT8. Peut-\u00eatre un peu de CW sur demande, mais pas en mode \u00ab pile-up \u00bb.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><b>( Maxim &#8211; OH7O \/ 21 AO\u00dbT 2026 )<\/b><\/p>\n<p style=\"text-align: justify;\"><b>29 ao\u00fbt 2026 &#8211; 8 septembre 2026 :<\/b><\/p>\n<p style=\"text-align: justify;\"><b>P29YY &#8211; Exp\u00e9dition DX \u00e0 Kavieng, province de Nouvelle-Irlande, Papouasie-Nouvelle-Guin\u00e9e (PNG), locator QI57jk, r\u00e9f\u00e9rence IOTA OC-008.<\/b><\/p>\n<p style=\"text-align: justify;\">Exp\u00e9dition DX en solitaire. Il ne s\u2019agit pas d\u2019une exp\u00e9dition de vacances, mais d\u2019une exp\u00e9dition DX en solitaire de haut niveau. Je me reposerai quelque part plus tard \ud83d\ude42<\/p>\n<p style=\"text-align: justify;\"><b>\u00c9tat au 21 ao\u00fbt :<\/b><\/p>\n<p style=\"text-align: justify;\">Il existe toujours beaucoup d\u2019incertitudes concernant l\u2019importation et l\u2019exportation du mat\u00e9riel. Par cons\u00e9quent, l\u2019exp\u00e9dition DX pourrait ne pas commencer, avec des cons\u00e9quences d\u00e9sagr\u00e9ables pour moi \u00e0 l\u2019a\u00e9roport une fois que je serai d\u00e9j\u00e0 en PNG.<\/p>\n<p style=\"text-align: justify;\">Oui, j\u2019ai la licence qui a \u00e9t\u00e9 d\u00e9livr\u00e9e en mars. Non, je n\u2019ai pas de documents d\u2019importation s\u00e9par\u00e9s pour mes radios, mes appareils de mesure du ROS et mes antennes. De plus, la NICTA (le r\u00e9gulateur local) envoie des courriels alarmants et confus concernant les r\u00e9glementations et les sanctions encourues en cas d\u2019infraction. Personne ne sait exactement ce qu\u2019il en est.<\/p>\n<p style=\"text-align: justify;\">Les \u00e9changes par courriel sont extr\u00eamement lents et les r\u00e9ponses restent confuses, car diff\u00e9rentes sources fournissent des informations diff\u00e9rentes, y compris au sein m\u00eame de la NICTA. Ils ne r\u00e9pondent pas aux appels t\u00e9l\u00e9phoniques.<\/p>\n<p style=\"text-align: justify;\">J\u2019ai rencontr\u00e9 de nombreux probl\u00e8mes et subi de nombreux retards, m\u00eame pour obtenir un simple visa \u00e9lectronique, et j\u2019ai failli abandonner l\u2019exp\u00e9dition il y a deux jours, malgr\u00e9 l\u2019achat d\u2019un billet non remboursable. Je pourrais encore changer d\u2019avis, car les risques sont plus importants que lors de mes exp\u00e9ditions pr\u00e9c\u00e9dentes. Malgr\u00e9 tout, je prends l\u2019avion pour l\u2019instant. Mais toutes les quelques heures, de nouvelles informations apparaissent et pourraient compl\u00e8tement modifier ma d\u00e9cision.<\/p>\n<p style=\"text-align: justify;\">J\u2019esp\u00e8re donc que tout se passera au mieux et je prendrai l\u2019avion avec tous les documents dont je dispose. Mais rien ne garantit que l\u2019on m\u2019autorisera \u00e0 op\u00e9rer.<\/p>\n<p style=\"text-align: justify;\">Je mettrai \u00e0 jour le plan des fr\u00e9quences, etc., lorsque \u2014 et si \u2014 on m\u2019autorise \u00e0 op\u00e9rer. Avec autant d\u2019obstacles, on devient facilement superstitieux.<\/p>\n<p style=\"text-align: justify;\">73, &#8211; Claude ON4CN<\/p>\n<p style=\"text-align: justify;\">Info de la Source de EA1CS <a href=\"http:\/\/ea1cs.blogspot.com\/\" target=\"_blank\"><b><span style=\"color: #ff0000;\"> ICI<\/span><\/b><\/a><\/p>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Article traduite en Fran\u00e7ais via Google Translate Information P29YY, Papouasie-Nouvelle-Guin\u00e9e Le 02 Septembre 2026 ( Maxim \/ 1er SEPTEMBRE 2026 ) Il est extr\u00eamement frustrant de devoir courir apr\u00e8s le personnel et les supplier de me donner de l\u2019\u00e9lectricit\u00e9, en leur rappelant et en leur demandant encore et encore. \u00ab Dans 5 minutes \u00bb, et &hellip; <a href=\"http:\/\/www.on4cn.be\/blog_radio\/2026\/09\/02\/information-p29yy-papouasie-nouvelle-guinee-3\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Information P29YY, Papouasie-Nouvelle-Guin\u00e9e&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,12,22,17,24,25],"tags":[],"class_list":["post-23888","post","type-post","status-publish","format-standard","hentry","category-dx","category-expedition-dx","category-infos-dx","category-iota","category-trafic-radio","category-trafic-radioamatuer"],"_links":{"self":[{"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/posts\/23888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/comments?post=23888"}],"version-history":[{"count":1,"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/posts\/23888\/revisions"}],"predecessor-version":[{"id":23889,"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/posts\/23888\/revisions\/23889"}],"wp:attachment":[{"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/media?parent=23888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/categories?post=23888"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.on4cn.be\/blog_radio\/wp-json\/wp\/v2\/tags?post=23888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}